{"id":13127,"date":"2019-10-15T18:00:04","date_gmt":"2019-10-15T16:00:04","guid":{"rendered":"https:\/\/www.lesgets.com\/?post_type=document&#038;p=13127"},"modified":"2020-08-27T09:15:53","modified_gmt":"2020-08-27T07:15:53","slug":"press-pack-winter-2019-2020","status":"publish","type":"document","link":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/","title":{"rendered":"Press pack winter 2019 &#8211; 2020"},"excerpt":{"rendered":"<p>Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism&#8230;<\/p>\n","protected":false},"template":"","categorie_document":[160],"class_list":["post-13127","document","type-document","status-publish","hentry","categorie_document-news-events-unmissable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Press pack winter 2019 - 2020 - Les Gets<\/title>\n<meta name=\"description\" content=\"Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Press pack winter 2019 - 2020 - Les Gets\" \/>\n<meta property=\"og:description\" content=\"Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Gets\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T07:15:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document\\\/press-pack-winter-2019-2020\\\/\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document\\\/press-pack-winter-2019-2020\\\/\",\"name\":\"Press pack winter 2019 - 2020 - Les Gets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#website\"},\"datePublished\":\"2019-10-15T16:00:04+00:00\",\"dateModified\":\"2020-08-27T07:15:53+00:00\",\"description\":\"Download the 2019\\\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document\\\/press-pack-winter-2019-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document\\\/press-pack-winter-2019-2020\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document\\\/press-pack-winter-2019-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"news - events - unmissable\",\"item\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/categorie_document\\\/news-events-unmissable\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Press pack winter 2019 &#8211; 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\",\"name\":\"Les Gets\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#organization\",\"name\":\"Les Gets\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/wp\\\/..\\\/app\\\/uploads\\\/2020\\\/06\\\/logo_lesgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesgets.com\\\/wp\\\/..\\\/app\\\/uploads\\\/2020\\\/06\\\/logo_lesgets.png\",\"width\":136,\"height\":115,\"caption\":\"Les Gets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Press pack winter 2019 - 2020 - Les Gets","description":"Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/","og_locale":"en_US","og_type":"article","og_title":"Press pack winter 2019 - 2020 - Les Gets","og_description":"Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...","og_url":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/","og_site_name":"Les Gets","article_modified_time":"2020-08-27T07:15:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/","url":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/","name":"Press pack winter 2019 - 2020 - Les Gets","isPartOf":{"@id":"https:\/\/www.lesgets.com\/en\/#website"},"datePublished":"2019-10-15T16:00:04+00:00","dateModified":"2020-08-27T07:15:53+00:00","description":"Download the 2019\/2020 winter press pack of the resort of Les Gets. You will find news, events, ski area information, outdoor activities, eco-tourism...","breadcrumb":{"@id":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesgets.com\/en\/blog\/document\/press-pack-winter-2019-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lesgets.com\/en\/"},{"@type":"ListItem","position":2,"name":"news - events - unmissable","item":"https:\/\/www.lesgets.com\/en\/blog\/categorie_document\/news-events-unmissable\/"},{"@type":"ListItem","position":3,"name":"Press pack winter 2019 &#8211; 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.lesgets.com\/en\/#website","url":"https:\/\/www.lesgets.com\/en\/","name":"Les Gets","description":"","publisher":{"@id":"https:\/\/www.lesgets.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesgets.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lesgets.com\/en\/#organization","name":"Les Gets","url":"https:\/\/www.lesgets.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesgets.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesgets.com\/wp\/..\/app\/uploads\/2020\/06\/logo_lesgets.png","contentUrl":"https:\/\/www.lesgets.com\/wp\/..\/app\/uploads\/2020\/06\/logo_lesgets.png","width":136,"height":115,"caption":"Les Gets"},"image":{"@id":"https:\/\/www.lesgets.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/document\/13127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/document"}],"about":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/types\/document"}],"wp:attachment":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/media?parent=13127"}],"wp:term":[{"taxonomy":"categorie_document","embeddable":true,"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/categorie_document?post=13127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}