{"id":14784,"date":"2020-04-30T10:27:41","date_gmt":"2020-04-30T08:27:41","guid":{"rendered":"https:\/\/www.lesgets.com\/document_brochure\/magin-les-gets-02\/"},"modified":"2020-07-01T10:36:57","modified_gmt":"2020-07-01T08:36:57","slug":"magin-les-gets-02","status":"publish","type":"document_brochure","link":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/","title":{"rendered":"Mag\u2019In Les Gets #02"},"excerpt":{"rendered":"<p>Discover the 2nd issue of Les Gets Mag&#8217;In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020. <\/p>\n","protected":false},"template":"","categorie_document":[123],"class_list":["post-14784","document_brochure","type-document_brochure","status-publish","hentry","categorie_document-magazine-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mag\u2019In Les Gets #02 - Les Gets<\/title>\n<meta name=\"description\" content=\"Discover the 2nd issue of Les Gets Mag&#039;In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mag\u2019In Les Gets #02 - Les Gets\" \/>\n<meta property=\"og:description\" content=\"Discover the 2nd issue of Les Gets Mag&#039;In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Gets\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-01T08:36:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document_brochure\\\/magin-les-gets-02\\\/\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document_brochure\\\/magin-les-gets-02\\\/\",\"name\":\"Mag\u2019In Les Gets #02 - Les Gets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#website\"},\"datePublished\":\"2020-04-30T08:27:41+00:00\",\"dateModified\":\"2020-07-01T08:36:57+00:00\",\"description\":\"Discover the 2nd issue of Les Gets Mag'In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \\\/ Summer-Fall 2020.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document_brochure\\\/magin-les-gets-02\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document_brochure\\\/magin-les-gets-02\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/document_brochure\\\/magin-les-gets-02\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazine\",\"item\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/blog\\\/categorie_document\\\/magazine-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mag\u2019In Les Gets #02\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\",\"name\":\"Les Gets\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#organization\",\"name\":\"Les Gets\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lesgets.com\\\/wp\\\/..\\\/app\\\/uploads\\\/2020\\\/06\\\/logo_lesgets.png\",\"contentUrl\":\"https:\\\/\\\/www.lesgets.com\\\/wp\\\/..\\\/app\\\/uploads\\\/2020\\\/06\\\/logo_lesgets.png\",\"width\":136,\"height\":115,\"caption\":\"Les Gets\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lesgets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mag\u2019In Les Gets #02 - Les Gets","description":"Discover the 2nd issue of Les Gets Mag'In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/","og_locale":"en_US","og_type":"article","og_title":"Mag\u2019In Les Gets #02 - Les Gets","og_description":"Discover the 2nd issue of Les Gets Mag'In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020.","og_url":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/","og_site_name":"Les Gets","article_modified_time":"2020-07-01T08:36:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/","url":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/","name":"Mag\u2019In Les Gets #02 - Les Gets","isPartOf":{"@id":"https:\/\/www.lesgets.com\/en\/#website"},"datePublished":"2020-04-30T08:27:41+00:00","dateModified":"2020-07-01T08:36:57+00:00","description":"Discover the 2nd issue of Les Gets Mag'In, the annual magazine of Les Gets Tourisme. Issue #02 Winter-Spring 2019-2020 \/ Summer-Fall 2020.","breadcrumb":{"@id":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesgets.com\/en\/blog\/document_brochure\/magin-les-gets-02\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lesgets.com\/en\/"},{"@type":"ListItem","position":2,"name":"Magazine","item":"https:\/\/www.lesgets.com\/en\/blog\/categorie_document\/magazine-en\/"},{"@type":"ListItem","position":3,"name":"Mag\u2019In Les Gets #02"}]},{"@type":"WebSite","@id":"https:\/\/www.lesgets.com\/en\/#website","url":"https:\/\/www.lesgets.com\/en\/","name":"Les Gets","description":"","publisher":{"@id":"https:\/\/www.lesgets.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesgets.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lesgets.com\/en\/#organization","name":"Les Gets","url":"https:\/\/www.lesgets.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lesgets.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesgets.com\/wp\/..\/app\/uploads\/2020\/06\/logo_lesgets.png","contentUrl":"https:\/\/www.lesgets.com\/wp\/..\/app\/uploads\/2020\/06\/logo_lesgets.png","width":136,"height":115,"caption":"Les Gets"},"image":{"@id":"https:\/\/www.lesgets.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/document_brochure\/14784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/document_brochure"}],"about":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/types\/document_brochure"}],"wp:attachment":[{"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/media?parent=14784"}],"wp:term":[{"taxonomy":"categorie_document","embeddable":true,"href":"https:\/\/www.lesgets.com\/en\/wp-json\/wp\/v2\/categorie_document?post=14784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}